{"id":9323,"date":"2022-03-08T16:16:24","date_gmt":"2022-03-08T15:16:24","guid":{"rendered":"https:\/\/cst.cat\/docencia\/%docencies%\/medicina\/geriatria\/"},"modified":"2026-03-09T13:03:22","modified_gmt":"2026-03-09T12:03:22","slug":"geriatria","status":"publish","type":"docencia","link":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/","title":{"rendered":"Geriatr\u00eda"},"content":{"rendered":"\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"273\" height=\"183\" src=\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg\" alt=\"\" class=\"wp-image-3461\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"entradeta\">El Servicio de Geriatr\u00eda del Consorcio Sanitario de Terrassa se acredit\u00f3 como Unidad Docente en 2008 ofreciendo 2 plazas de m\u00e9dico interno en Geriatr\u00eda por a\u00f1o. Desde el a\u00f1o 2019 hemos estado tambi\u00e9n acreditados como Unidad Docente Multiprofesional de Geriatr\u00eda con la acreditaci\u00f3n para formar a dos residentes de enfermer\u00eda especialistas en Geriatr\u00eda. El Servicio est\u00e1 formado por un Equipo de profesionales j\u00f3venes en los que el rigor, el esp\u00edritu docente, la \u00e9tica, el respeto, el trabajo en Equipo y la actividad multidisciplinar son valores y principios b\u00e1sicos.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La Geriatr\u00eda es una Especialidad que se caracteriza por tener una visi\u00f3n global e integral del paciente, de la enfermedad y del n\u00facleo paciente-familia. La transversalidad, la coordinaci\u00f3n entre niveles asistenciales y la garant\u00eda del continuo asistencial son caracter\u00edsticas imprescindibles para su desarrollo. El Consorcio Sanitario de Terrassa es una Organizaci\u00f3n Sanitaria Integral (OSI) es decir, organizaci\u00f3n con todos los niveles Asistenciales (Atenci\u00f3n Primaria, Atenci\u00f3n Intermedia, Residencia Geri\u00e1trica, Hospital de Agudos y Consultas Externas de Atenci\u00f3n Especializada) que valora la Geriatr\u00eda como una Especialidad de gran futuro con un largo recorrido por llevar a cabo.<\/p>\n\n\n\n<p>La Unidad Docente Multiprofesional, conjuntamente con el \u00c1rea de Conocimiento y Docencia, velan por el cumplimiento de tu proyecto formativo garantizando el Programa marcado por el Plan Nacional de Especialidades. Est\u00e1n previstas rotaciones por los diferentes Servicios Asistenciales y por todos los dispositivos de Geriatr\u00eda (Unidad de Agudos, Unidad de Subagudos, Unidad de Ortogeriatria, Unidad de Media Estancia de Rehabilitaci\u00f3n y de Cuidados Paliativos, Unidad de Larga Estancia de Psicogeriatr\u00eda, Unidad de Larga Estancia Convencional, Consultas Externas de Valoraci\u00f3n, Equipo de soporte a las residencias y equipo de soporte hospitalario) y rotaciones externas. Sin embargo, desde la propia Unidad Docente y desde el \u00c1rea del Conocimiento y Docencia se impulsan l\u00edneas de investigaci\u00f3n y de investigaci\u00f3n.<\/p>\n\n\n\n<p>A continuaci\u00f3n encontrar\u00e1s de forma m\u00e1s detallada c\u00f3mo se desarrollan los a\u00f1os de formaci\u00f3n en Geriatr\u00eda en el Consorcio Sanitario de Terrassa. Le animamos a compartir su experiencia profesional con nuestros equipos.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\r\n    <!-- block: cst-accordion-redesign -->\r\n    <section class=\"block-cst-faqs block-cst-accordion  uni-cnt\" style=\"\">\r\n        <div class=\"cst-accordion-wrapper no-image\">\r\n\r\n            \r\n            <div class=\"cst-accordion-content\">\r\n                \r\n                \r\n                                    <ul class=\"demo-accordion accordionjs\" data-active-index=\"false\">\r\n                                                    <!-- Section 1 -->\r\n                            <li>\r\n                                <div>\r\n                                    <h3>Programa oficial de especialidad (POE)<\/h3>\r\n                                <\/div>\r\n                                <div>\r\n                                    <p>La Formaci\u00f3n Sanitaria Especializada (FSE) tiene como objetivo conseguir especialistas competentes que den respuesta a las necesidades de la sociedad en el \u00e1mbito de la salud. Las competencias que debe adquirir el especialista en formaci\u00f3n quedan reflejadas de forma m\u00e1s o menos espec\u00edfica en los POE, que deben ser, por tanto, la gu\u00eda a seguir por las diferentes Unidades Docentes en la formaci\u00f3n de sus residentes. La adaptaci\u00f3n de los POE a la realidad de cada centro constituir\u00e1 el Programa o Gu\u00eda formativa tipo.<\/p>\n<p class=\"but-content\"><a href=\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/POE-geriatria.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">POE<\/a><\/p>\n                                <\/div>\r\n                            <\/li>\r\n                                                    <!-- Section 1 -->\r\n                            <li>\r\n                                <div>\r\n                                    <h3>Gu\u00eda formativa tipo<\/h3>\r\n                                <\/div>\r\n                                <div>\r\n                                    <p>La gu\u00eda formativa est\u00e1 basada en el programa oficial de la especialidad y supone una adaptaci\u00f3n de sus principales puntos a las caracter\u00edsticas de la UD. Sus objetivos son: adaptar el programa oficial al contexto de la unidad docente, servir de programa formativo com\u00fan para todos los residentes del servicio, sentar las bases de planificaci\u00f3n del programa formativo a lo largo de toda la residencia, concretar los principios fundamentales de los procesos formativos y servir de gu\u00eda para la elaboraci\u00f3n de los planes individuales anuales de cada residente.<\/p>\n<p class=\"but-content\"><a href=\"https:\/\/cst.cat\/wp-content\/uploads\/2026\/03\/PLA-DOC-20_Guia-formativa-geriatria-medicina_Ver07.pdf\">Guia formativa<\/a><\/p>\n                                <\/div>\r\n                            <\/li>\r\n                                                    <!-- Section 1 -->\r\n                            <li>\r\n                                <div>\r\n                                    <h3>Protocolo de supervisi\u00f3n<\/h3>\r\n                                <\/div>\r\n                                <div>\r\n                                    <p>El sistema de formaci\u00f3n por residencia implica la asunci\u00f3n progresiva de responsabilidades y un nivel decreciente de supervisi\u00f3n. A medida que el residente avanza en la adquisici\u00f3n de las competencias previstas en el programa formativo de la especialidad, va alcanzando el grado de responsabilidad inherente al ejercicio aut\u00f3nomo de la especialidad. La supervisi\u00f3n de los residentes de primer a\u00f1o ser\u00e1 de presencia f\u00edsica (RD 183\/2008, de 8 de febrero). A partir del segundo a\u00f1o la supervisi\u00f3n ser\u00e1 decreciente hasta la total autonom\u00eda al finalizar la residencia.<\/p>\n<p class=\"but-content\"><a href=\"https:\/\/cst.cat\/wp-content\/uploads\/2022\/04\/Consorci-Sanitari-Terrassa-Medicina-Geriatria-PROTOCOL-SUPERVISIO.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Protocolo supervisi\u00f3n residente<\/a><\/p>\n                                <\/div>\r\n                            <\/li>\r\n                                                    <!-- Section 1 -->\r\n                            <li>\r\n                                <div>\r\n                                    <h3>Programa individual de formaci\u00f3n (PIF)<\/h3>\r\n                                <\/div>\r\n                                <div>\r\n                                    <p>El Programa individual de formaci\u00f3n (PIF) es el documento\/instrumento que recoge la planificaci\u00f3n temporal de las actividades formativas te\u00f3rico-pr\u00e1cticas, que debe realizar el residente en cada uno de los per\u00edodos formativos a lo largo de toda la residencia. Sirve para organizar, secuenciar, graduar y adaptar los aprendizajes a las caracter\u00edsticas de cada residente. Permite al tutor tener una visi\u00f3n de conjunto de todas las actividades de formaci\u00f3n en las que debe participar el residente, para facilitar una correcta coordinaci\u00f3n e implicaci\u00f3n de todos los agentes involucrados en el proceso.Permite al residente conocer desde el primer momento cu\u00e1les son las actividades en las que debe participar, reduciendo el nivel de incertidumbre, estableciendo y reforzando compromisos docentes, y organizando el tiempo y los recursos de la forma m\u00e1s eficiente para que sea consciente de su propio proceso de aprendizaje. El tutor de la Unidad docente (UD) entregar\u00e1 el PIF al residente al inicio de su formaci\u00f3n junto con el Programa o ficial de la especialidad y la gu\u00eda de la UD.<\/p>\n                                <\/div>\r\n                            <\/li>\r\n                                                    <!-- Section 1 -->\r\n                            <li>\r\n                                <div>\r\n                                    <h3>Libro del residente<\/h3>\r\n                                <\/div>\r\n                                <div>\r\n                                    <p>El libro del residente es un registro individual de las actividades que realiza cada residente durante su per\u00edodo formativo. Es el instrumento que evidencia el proceso formativo del residente, al que se incorporar\u00e1n los datos cuantitativos y cualitativos que se valorar\u00e1n en la evaluaci\u00f3n. Debe ser un instrumento de autoaprendizaje que favorezca la reflexi\u00f3n individual y conjunta con el tutor, con el fin de asegurar la adecuaci\u00f3n de las actividades llevadas a cabo por el residente y hacer posible la correcci\u00f3n de d\u00e9ficits formativos. Es propiedad del residente ,\u00a0\u00a0que debe rellenarla con la ayuda y la supervisi\u00f3n del tutor. Los datos que contenga estar\u00e1n sujetos a la legislaci\u00f3n vigente sobre protecci\u00f3n de datos personales y secreto profesional. Tiene car\u00e1cter obligatorio (RD 183\/2008, de 8 de febrero). La Comisi\u00f3n Nacional de cada especialidad tiene el encargo de elaborarlo.<\/p>\n                                <\/div>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n    <!-- end block: cst-accordion-redesign -->\r\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\r\n    <!-- block: contactar enlaces -->\r\n            <section class=\"block-contactar-enlaces  contact-sec sense-marge\">\r\n            <div class=\"row\">\r\n                                    <div class=\"chead\">DATOS DE CONTACTO<\/div>\r\n                                <ul class=\"contact-lst\">\r\n                                            <li class=\"mail \">\r\n                                                            <h2>Jefe del Servicio de Geriatr\u00eda<\/h2>\r\n                                                        <p><strong>Dra. Mireia Llonch Masriera<br \/>\n<\/strong><a href=\"mailto:mllonch@cst.cat\" target=\"_blank\" rel=\"noopener\">mllonch@cst.cat<\/a><\/p>\n                        <\/li>\r\n                                            <li class=\"mail \">\r\n                                                            <h2>Secretar\u00eda del Servicio de Geratr\u00eda<\/h2>\r\n                                                        <p><strong>Sra. Neus Carreras<\/strong><br \/>\n<a href=\"mailto:sconvalescencia@cst.cat\" target=\"_blank\" rel=\"noopener\">sconvalescencia@cst.cat<\/a><\/p>\n<p>T. 93 731 00 07 ext. 2870<\/p>\n                        <\/li>\r\n                                            <li class=\"mail \">\r\n                                                            <h2>Tutores del Servicio de Geriatr\u00eda<\/h2>\r\n                                                        <p><strong>Dr. Sami Loutfi\u00a0<\/strong><br \/>\n<a href=\"mailto:sloutfi@cst.cat\" target=\"_blank\" rel=\"noopener\">sloutfi@cst.cat<\/a><\/p>\n<p><strong>Dr. Santiago Castej\u00f3n<br \/>\n<\/strong><a href=\"mailto:scastejon@cst.cat\" target=\"_blank\" rel=\"noopener\">scastejon@cst.cat<\/a><\/p>\n<p><strong>Dra. Georgina Cerd\u00e0<br \/>\n<\/strong><a href=\"mailto:gcerda@cst.cat\" target=\"_blank\" rel=\"noopener\">gcerda@cst.cat<\/a><\/p>\n<p>&nbsp;<\/p>\n                        <\/li>\r\n                                    <\/ul>\r\n            <\/div>\r\n        <\/section>\r\n        <!-- end block: contactar enlaces -->\r\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"parent":9313,"menu_order":4,"template":"","tags":[],"docencies":[204],"class_list":["post-9323","docencia","type-docencia","status-publish","hentry","docencies-residentes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geriatr\u00eda - CST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geriatr\u00eda - CST\" \/>\n<meta property=\"og:description\" content=\"El Servicio de Geriatr\u00eda del Consorcio Sanitario de Terrassa se acredit\u00f3 como Unidad Docente en 2008 ofreciendo 2 plazas de m\u00e9dico interno en Geriatr\u00eda por a\u00f1o. Desde el a\u00f1o 2019 hemos estado tambi\u00e9n acreditados como Unidad Docente Multiprofesional de Geriatr\u00eda con la acreditaci\u00f3n para formar a dos residentes de enfermer\u00eda especialistas en Geriatr\u00eda. El Servicio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/\" \/>\n<meta property=\"og:site_name\" content=\"CST\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T12:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/\",\"url\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/\",\"name\":\"Geriatr\u00eda - CST\",\"isPartOf\":{\"@id\":\"https:\/\/cst.cat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg\",\"datePublished\":\"2022-03-08T15:16:24+00:00\",\"dateModified\":\"2026-03-09T12:03:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#primaryimage\",\"url\":\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg\",\"contentUrl\":\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/cst.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medicina\",\"item\":\"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geriatr\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cst.cat\/es\/#website\",\"url\":\"https:\/\/cst.cat\/es\/\",\"name\":\"CST\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cst.cat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cst.cat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cst.cat\/es\/#organization\",\"name\":\"Consorci Sanitari de Terrassa\",\"url\":\"https:\/\/cst.cat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cst.cat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/09\/logo-header.svg\",\"contentUrl\":\"https:\/\/cst.cat\/wp-content\/uploads\/2021\/09\/logo-header.svg\",\"width\":90,\"height\":32,\"caption\":\"Consorci Sanitari de Terrassa\"},\"image\":{\"@id\":\"https:\/\/cst.cat\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geriatr\u00eda - CST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/","og_locale":"es_ES","og_type":"article","og_title":"Geriatr\u00eda - CST","og_description":"El Servicio de Geriatr\u00eda del Consorcio Sanitario de Terrassa se acredit\u00f3 como Unidad Docente en 2008 ofreciendo 2 plazas de m\u00e9dico interno en Geriatr\u00eda por a\u00f1o. Desde el a\u00f1o 2019 hemos estado tambi\u00e9n acreditados como Unidad Docente Multiprofesional de Geriatr\u00eda con la acreditaci\u00f3n para formar a dos residentes de enfermer\u00eda especialistas en Geriatr\u00eda. El Servicio [&hellip;]","og_url":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/","og_site_name":"CST","article_modified_time":"2026-03-09T12:03:22+00:00","og_image":[{"url":"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/","url":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/","name":"Geriatr\u00eda - CST","isPartOf":{"@id":"https:\/\/cst.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#primaryimage"},"image":{"@id":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#primaryimage"},"thumbnailUrl":"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg","datePublished":"2022-03-08T15:16:24+00:00","dateModified":"2026-03-09T12:03:22+00:00","breadcrumb":{"@id":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#primaryimage","url":"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg","contentUrl":"https:\/\/cst.cat\/wp-content\/uploads\/2021\/12\/ud-medicina-geriatria.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/geriatria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/cst.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Medicina","item":"https:\/\/cst.cat\/es\/docencia\/residentes\/medicina\/"},{"@type":"ListItem","position":3,"name":"Geriatr\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/cst.cat\/es\/#website","url":"https:\/\/cst.cat\/es\/","name":"CST","description":"","publisher":{"@id":"https:\/\/cst.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cst.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cst.cat\/es\/#organization","name":"Consorci Sanitari de Terrassa","url":"https:\/\/cst.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cst.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cst.cat\/wp-content\/uploads\/2021\/09\/logo-header.svg","contentUrl":"https:\/\/cst.cat\/wp-content\/uploads\/2021\/09\/logo-header.svg","width":90,"height":32,"caption":"Consorci Sanitari de Terrassa"},"image":{"@id":"https:\/\/cst.cat\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/docencia\/9323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/docencia"}],"about":[{"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/types\/docencia"}],"up":[{"embeddable":true,"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/docencia\/9313"}],"wp:attachment":[{"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/media?parent=9323"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/tags?post=9323"},{"taxonomy":"docencies","embeddable":true,"href":"https:\/\/cst.cat\/es\/wp-json\/wp\/v2\/docencies?post=9323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}